{"id":1077,"date":"2020-08-09T15:59:15","date_gmt":"2020-08-09T15:59:15","guid":{"rendered":"http:\/\/repeople.bigmountain.studio\/?p=1077"},"modified":"2024-11-13T15:19:26","modified_gmt":"2024-11-13T15:19:26","slug":"reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo","status":"publish","type":"post","link":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/","title":{"rendered":"Reflexiones sobre el proyecto de Ley sobre el teletrabajo"},"content":{"rendered":"\n<p><span style=\"font-weight: 400;\">El pasado 6 de junio 2020 comenzaba el plazo de la consulta p\u00fablica previa a la elaboraci\u00f3n de un proyecto normativo sobre la modificaci\u00f3n y elaboraci\u00f3n de las condiciones para prestar trabajo por cuenta ajena a distancia. La verdad es que nunca antes particip\u00e9 en un proceso de consulta p\u00fablica, pero esta era una oportunidad que no pod\u00eda dejar pasar.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Me habr\u00eda encantado participar en una propuesta conjunta con diferentes profesionales en Espa\u00f1a con los que colaboro activamente, pero el plazo l\u00edmite del 22 de junio (poco m\u00e1s de 1 semana desde que recib\u00ed la noticia) se me vino encima antes de lo previsto y tuve que apurar el \u00faltimo d\u00eda para poder incorporar algunas ideas propias que paso a compartirles. Les invito a compartir sus propias aportaciones y opiniones en los comentarios.<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"850\" height=\"564\" src=\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/proyecto-de-ley-sobre-el-teletrabajo.webp\" alt=\"proyecto de ley sobre el teletrabajo\" class=\"wp-image-14609\" srcset=\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/proyecto-de-ley-sobre-el-teletrabajo.webp 850w, https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/proyecto-de-ley-sobre-el-teletrabajo-300x199.webp 300w, https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/proyecto-de-ley-sobre-el-teletrabajo-768x510.webp 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Temporalidad<\/b><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Creo que el marco regulatorio debe contemplar el teletrabajo a tiempo parcial pero tambi\u00e9n a tiempo completo. Seg\u00fan entiendo en el apartado \u201ca) El car\u00e1cter temporal del teletrabajo\u201d no se contemplan las empresas que carecen de un centro de trabajo ( empresas distribuidas) y por lo tanto el teletrabajo no es una opci\u00f3n, es la \u00fanica opci\u00f3n. Tambi\u00e9n hay muchos casos en los que los teletrabajadores nunca asisten al centro de trabajo debido a su localizaci\u00f3n ( pueden estar muy lejos del centro de trabajo ) o incluso a sus limitaciones f\u00edsicas ( recordemos que una de las grandes ventajas del teletrabajo es la inclusi\u00f3n de personas discapacitadas f\u00edsicas que tiene limitaciones de movilidad y que no pueden desplazarse al centro de trabajo).&nbsp;<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Equipamiento<\/b><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Cuando hablamos de equipamiento para desarrollar la actividad en remoto, recomendamos que el empleado tenga derecho a solicitar a la empresa los equipos inform\u00e1ticos necesarios , as\u00ed como dotar de la conectividad adecuada, pero de manera m\u00e1s importante facilitar aquellos elementos que permiten al empleado tener un puesto de trabajo ergon\u00f3mico y que evite posibles problemas de salud ; silla ergon\u00f3mica, mesa de trabajo, etc. La empresa tambi\u00e9n deber\u00e1 cubrir la contrataci\u00f3n de un espacio flexible de trabajo ( coworking , business center ) cuando el empleado decida desarrollar su trabajo desde un espacio de coworking que incorpore todas las facilidades para teletrabajar adecuadamente.&nbsp;<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Organizaci\u00f3n del trabajo&nbsp;<\/b><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Cuando otorgamos al teletrabajador la libertad de organizar su tiempo de trabajo, debemos contemplar la necesaria libertad horaria y flexibilidad de acuerdo a las responsabilidades de su puesto. Si formulamos una normativa que simule la normativa actual del puesto de trabajo , obligando a \u201cfichar\u201d en un horario estricto , nos estaremos cargando la principal ventaja que ofrece el teletrabajo al trabajador, de poder adecuar su horario a sus necesidades personales. Por otra parte, si es relevante contabilizar el compromiso de horas de trabajo que se haya estipulado por contrato o por ley , para evitar el sobre-trabajo. Esta contabilizaci\u00f3n la recomendamos hacer mensual o en su defecto semanal.&nbsp;&nbsp;<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Deslocalizaci\u00f3n&nbsp;<\/b><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Una de las grandes ventajas del teletrabajo es la deslocalizaci\u00f3n de los trabajadores, optando muchos de ellos por un estilo de vida n\u00f3mada ( n\u00f3madas digitales ) o incluso por establecerse de manera temporal o indefinida en otro pa\u00eds , bien sea de la Uni\u00f3n Europea o no ( seg\u00fan la regulaci\u00f3n de visados permita a cada trabajador ). La nueva normativa debe contemplar esta posibilidad cada vez m\u00e1s frecuente entre los profesionales m\u00e1s j\u00f3venes, cubriendo aspectos como la necesidad de tener un seguro de salud internacional o como resolver su deslocalizaci\u00f3n temporal o permanente desde un punto de vista normativo. Tambi\u00e9n debemos considerar a todos aquellos teletrabajadores de empresas de la Uni\u00f3n Europea, que deciden instalarse temporalmente o indefinidamente en nuestro pa\u00eds, por las implicaciones que esto conlleva de cara a la seguridad social, tributaci\u00f3n , etc. teniendo en cuenta que esto representa una oportunidad muy interesante para nuestro Pa\u00eds desde un punto de vista socio-econ\u00f3mico.&nbsp;<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Formaci\u00f3n&nbsp;<\/b><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">La formaci\u00f3n de los empleados que teletrabajan como de sus directivos para que aprendan a gestionar las ventajas y los inconvenientes que genera el teletrabajo, para que aprendan a cambiar los modelos de direcci\u00f3n presencialistas por otros basados en la consecuci\u00f3n de objetivos y en la direcci\u00f3n de personas , debe ser un aspecto que se incluya como obligatorio para aquellas empresas que adopten este modelo de trabajo. Para el empleado factores como pueden ser combatir el aislamiento, mejorar la comunicaci\u00f3n o aprender habilidades de gesti\u00f3n del tiempo y de organizaci\u00f3n personal, son requisitos para que puedan desarrollar una carrera profesional exitosa como teletrabajadores. En el \u00e1mbito directivo, la gesti\u00f3n de equipos virtuales es una de las materias menos tratadas en centros de formaci\u00f3n p\u00fablico y privados incluso de primer nivel, y son fundamentales para el \u00e9xito de empresas que adopten esta din\u00e1mica organizativa.&nbsp;<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Desconexi\u00f3n&nbsp;<\/b><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Precisamente debido a las malas pr\u00e1cticas generadas por falta de formaci\u00f3n de directivos y empleados a la hora de teletrabajar, el derecho de desconexi\u00f3n es importante que quede definido en esta ley para que permita a ambos conciliar su vida personal con el trabajo y evitar problemas frecuentes entre teletrabajadores como son el exceso de trabajo que acaba frecuentemente en desequilibrios psicol\u00f3gicos . Este derecho de desconexi\u00f3n debe ser tambi\u00e9n flexible acorde a las libertad que otorgamos a cada teletrabajador para organizarse libremente.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Derecho a teletrabajar<\/b><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">La posibilidad de teletrabajar al menos de manera parcial debe ser un derecho del trabajador que tenga un puesto que lo permita, en aquellas circunstancias que se consideren justificadas como puedan ser el cuidado de ni\u00f1os\/familiares , motivos derivados de problemas de salud ( enfermedad \/ pandemia \/ limitaci\u00f3n de movilidad ) o incluso los derivados de restricciones de movilidad por problemas de poluci\u00f3n ambiental<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 6 de junio 2020 comenzaba el plazo de la consulta p\u00fablica previa a la elaboraci\u00f3n de un proyecto normativo sobre la modificaci\u00f3n y elaboraci\u00f3n de las condiciones para prestar trabajo por cuenta ajena a distancia. La verdad es que nunca antes particip\u00e9 en un proceso de consulta p\u00fablica, pero esta era una oportunidad [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":14939,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"Reflexiones sobre el proyecto de Ley del teletrabajo","_yoast_wpseo_metadesc":"Reflexiones sobre el proyecto de Ley sobre el teletrabajo de Nacho Rodr\u00edguez, CEO y Fundador de repeople.&#x1F4DC;repeople","footnotes":""},"categories":[150,19],"tags":[37,39],"class_list":["post-1077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-impacto","tag-ley-teletrabajo","tag-normativa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reflexiones sobre el proyecto de Ley del teletrabajo<\/title>\n<meta name=\"description\" content=\"Reflexiones sobre el proyecto de Ley sobre el teletrabajo de Nacho Rodr\u00edguez, CEO y Fundador de repeople.&#x1F4DC;repeople\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reflexiones sobre el proyecto de Ley sobre el teletrabajo\" \/>\n<meta property=\"og:description\" content=\"Reflexiones sobre el proyecto de Ley sobre el teletrabajo, este es el post que deja por aqu\u00ed Nacho Rodr\u00edguez con algunos puntos destacados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/\" \/>\n<meta property=\"og:site_name\" content=\"repeople\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rePeople.co\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-09T15:59:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-13T15:19:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/maarten-van-den-heuvel-_pc8aMbI9UQ-unsplash-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nacho Rodr\u00edguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Reflexiones sobre el proyecto de Ley sobre el teletrabajo\" \/>\n<meta name=\"twitter:description\" content=\"Reflexiones sobre el proyecto de Ley sobre el teletrabajo, este es el post que deja por aqu\u00ed Nacho Rodr\u00edguez con algunos puntos destacados.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/maarten-van-den-heuvel-_pc8aMbI9UQ-unsplash-1.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@repeopleco\" \/>\n<meta name=\"twitter:site\" content=\"@repeopleco\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho Rodr\u00edguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/\"},\"author\":{\"name\":\"Nacho Rodr\u00edguez\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/2c2411632700a7c10a40d1b46816ee50\"},\"headline\":\"Reflexiones sobre el proyecto de Ley sobre el teletrabajo\",\"datePublished\":\"2020-08-09T15:59:15+00:00\",\"dateModified\":\"2024-11-13T15:19:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/\"},\"wordCount\":989,\"publisher\":{\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/Reflexiones-sobre-el-proyecto-de-Ley-sobre-el-teletrabajo.webp\",\"keywords\":[\"Ley Teletrabajo\",\"Normativa\"],\"articleSection\":[\"Blog\",\"Impacto\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/\",\"url\":\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/\",\"name\":\"Reflexiones sobre el proyecto de Ley del teletrabajo\",\"isPartOf\":{\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/Reflexiones-sobre-el-proyecto-de-Ley-sobre-el-teletrabajo.webp\",\"datePublished\":\"2020-08-09T15:59:15+00:00\",\"dateModified\":\"2024-11-13T15:19:26+00:00\",\"description\":\"Reflexiones sobre el proyecto de Ley sobre el teletrabajo de Nacho Rodr\u00edguez, CEO y Fundador de repeople.&#x1F4DC;repeople\",\"breadcrumb\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#primaryimage\",\"url\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/Reflexiones-sobre-el-proyecto-de-Ley-sobre-el-teletrabajo.webp\",\"contentUrl\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/Reflexiones-sobre-el-proyecto-de-Ley-sobre-el-teletrabajo.webp\",\"width\":900,\"height\":600,\"caption\":\"Reflexiones sobre el proyecto de Ley sobre el teletrabajo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.repeople.co\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reflexiones sobre el proyecto de Ley sobre el teletrabajo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#website\",\"url\":\"https:\/\/www.repeople.co\/es\/en\/\",\"name\":\"repeople\",\"description\":\"Dise\u00f1ando ecosistemas para teletrabajadores\",\"publisher\":{\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#organization\"},\"alternateName\":\"repeople\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.repeople.co\/es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#organization\",\"name\":\"repeople\",\"alternateName\":\"repeople\",\"url\":\"https:\/\/www.repeople.co\/es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-logo-2.png\",\"contentUrl\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-logo-2.png\",\"width\":762,\"height\":220,\"caption\":\"repeople\"},\"image\":{\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/rePeople.co\/\",\"https:\/\/x.com\/repeopleco\",\"https:\/\/www.instagram.com\/repeopleco\/\",\"https:\/\/www.linkedin.com\/company\/repeopleco\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/2c2411632700a7c10a40d1b46816ee50\",\"name\":\"Nacho Rodr\u00edguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2024\/10\/nacho-Rodriguez.webp\",\"contentUrl\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2024\/10\/nacho-Rodriguez.webp\",\"caption\":\"Nacho Rodr\u00edguez\"},\"description\":\"CEO &amp; Fundador de Repeople\",\"sameAs\":[\"https:\/\/www.repeople.co\/\",\"https:\/\/www.linkedin.com\/in\/nachorodriguezc\/\"],\"url\":\"https:\/\/www.repeople.co\/es\/author\/nacho\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reflexiones sobre el proyecto de Ley del teletrabajo","description":"Reflexiones sobre el proyecto de Ley sobre el teletrabajo de Nacho Rodr\u00edguez, CEO y Fundador de repeople.&#x1F4DC;repeople","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/","og_locale":"es_ES","og_type":"article","og_title":"Reflexiones sobre el proyecto de Ley sobre el teletrabajo","og_description":"Reflexiones sobre el proyecto de Ley sobre el teletrabajo, este es el post que deja por aqu\u00ed Nacho Rodr\u00edguez con algunos puntos destacados.","og_url":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/","og_site_name":"repeople","article_publisher":"https:\/\/www.facebook.com\/rePeople.co\/","article_published_time":"2020-08-09T15:59:15+00:00","article_modified_time":"2024-11-13T15:19:26+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/maarten-van-den-heuvel-_pc8aMbI9UQ-unsplash-1.jpg","type":"image\/jpeg"}],"author":"Nacho Rodr\u00edguez","twitter_card":"summary_large_image","twitter_title":"Reflexiones sobre el proyecto de Ley sobre el teletrabajo","twitter_description":"Reflexiones sobre el proyecto de Ley sobre el teletrabajo, este es el post que deja por aqu\u00ed Nacho Rodr\u00edguez con algunos puntos destacados.","twitter_image":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/maarten-van-den-heuvel-_pc8aMbI9UQ-unsplash-1.jpg","twitter_creator":"@repeopleco","twitter_site":"@repeopleco","twitter_misc":{"Escrito por":"Nacho Rodr\u00edguez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#article","isPartOf":{"@id":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/"},"author":{"name":"Nacho Rodr\u00edguez","@id":"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/2c2411632700a7c10a40d1b46816ee50"},"headline":"Reflexiones sobre el proyecto de Ley sobre el teletrabajo","datePublished":"2020-08-09T15:59:15+00:00","dateModified":"2024-11-13T15:19:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/"},"wordCount":989,"publisher":{"@id":"https:\/\/www.repeople.co\/es\/en\/#organization"},"image":{"@id":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/Reflexiones-sobre-el-proyecto-de-Ley-sobre-el-teletrabajo.webp","keywords":["Ley Teletrabajo","Normativa"],"articleSection":["Blog","Impacto"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/","url":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/","name":"Reflexiones sobre el proyecto de Ley del teletrabajo","isPartOf":{"@id":"https:\/\/www.repeople.co\/es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#primaryimage"},"image":{"@id":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/Reflexiones-sobre-el-proyecto-de-Ley-sobre-el-teletrabajo.webp","datePublished":"2020-08-09T15:59:15+00:00","dateModified":"2024-11-13T15:19:26+00:00","description":"Reflexiones sobre el proyecto de Ley sobre el teletrabajo de Nacho Rodr\u00edguez, CEO y Fundador de repeople.&#x1F4DC;repeople","breadcrumb":{"@id":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#primaryimage","url":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/Reflexiones-sobre-el-proyecto-de-Ley-sobre-el-teletrabajo.webp","contentUrl":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/Reflexiones-sobre-el-proyecto-de-Ley-sobre-el-teletrabajo.webp","width":900,"height":600,"caption":"Reflexiones sobre el proyecto de Ley sobre el teletrabajo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.repeople.co\/es\/blog\/reflexiones-sobre-el-proyecto-de-ley-sobre-el-teletrabajo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.repeople.co\/es\/"},{"@type":"ListItem","position":2,"name":"Reflexiones sobre el proyecto de Ley sobre el teletrabajo"}]},{"@type":"WebSite","@id":"https:\/\/www.repeople.co\/es\/en\/#website","url":"https:\/\/www.repeople.co\/es\/en\/","name":"repeople","description":"Dise\u00f1ando ecosistemas para teletrabajadores","publisher":{"@id":"https:\/\/www.repeople.co\/es\/en\/#organization"},"alternateName":"repeople","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repeople.co\/es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.repeople.co\/es\/en\/#organization","name":"repeople","alternateName":"repeople","url":"https:\/\/www.repeople.co\/es\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repeople.co\/es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-logo-2.png","contentUrl":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-logo-2.png","width":762,"height":220,"caption":"repeople"},"image":{"@id":"https:\/\/www.repeople.co\/es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rePeople.co\/","https:\/\/x.com\/repeopleco","https:\/\/www.instagram.com\/repeopleco\/","https:\/\/www.linkedin.com\/company\/repeopleco"]},{"@type":"Person","@id":"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/2c2411632700a7c10a40d1b46816ee50","name":"Nacho Rodr\u00edguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/image\/","url":"https:\/\/www.repeople.co\/wp-content\/uploads\/2024\/10\/nacho-Rodriguez.webp","contentUrl":"https:\/\/www.repeople.co\/wp-content\/uploads\/2024\/10\/nacho-Rodriguez.webp","caption":"Nacho Rodr\u00edguez"},"description":"CEO &amp; Fundador de Repeople","sameAs":["https:\/\/www.repeople.co\/","https:\/\/www.linkedin.com\/in\/nachorodriguezc\/"],"url":"https:\/\/www.repeople.co\/es\/author\/nacho\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/posts\/1077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/comments?post=1077"}],"version-history":[{"count":7,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/posts\/1077\/revisions"}],"predecessor-version":[{"id":16666,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/posts\/1077\/revisions\/16666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/media\/14939"}],"wp:attachment":[{"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/media?parent=1077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/categories?post=1077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/tags?post=1077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}