{"id":5959,"date":"2021-12-03T10:52:06","date_gmt":"2021-12-03T10:52:06","guid":{"rendered":"https:\/\/www.repeople.co\/?p=5959"},"modified":"2024-10-30T08:18:59","modified_gmt":"2024-10-30T08:18:59","slug":"cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias","status":"publish","type":"post","link":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/","title":{"rendered":"Cerca de 400 personas de 29 pa\u00edses asistieron a la repeople Conference celebrada en las Islas Canarias"},"content":{"rendered":"<blockquote><p>Alemania, Irlanda, Reino Unido, Estados Unidos, Espa\u00f1a y otros muchos pa\u00edses conectaron con la repeople Conference de manera online<\/p><\/blockquote>\n<p>Cerca de 400 personas de 29 pa\u00edses han asistido esta semana a la sexta edici\u00f3n de la repeople Conference, el \u00fanico evento en Europa que analiza el trabajo remoto desde distintas perspectivas y este a\u00f1o, con especial hincapi\u00e9 en el punto de vista del mundo empresarial.<\/p>\n<p>Cada vez m\u00e1s, las empresas deben enfrentarse a nuevas formas de trabajo basadas en modelos de asistencia cien por cien presenciales, totalmente en remoto o h\u00edbridos. En ese sentido, la repeople Conference ha tratado de dar respuesta a todas aquellas dudas que surgen a las compa\u00f1\u00edas que, sobre todo desde que comenz\u00f3 la pandemia derivada de la Covid-19, han debido adaptarse a estos nuevos modelos de trabajo con preguntas como: \u00bfest\u00e1n preparadas las empresas para el trabajo distribuido?, \u00bfcu\u00e1l es el marco legal a la hora de contratar a personal que se encuentra desarrollando su labor desde otros pa\u00edses? o \u00bfc\u00f3mo deben gestionarse equipos en remoto?<\/p>\n<p>Estas y otras muchas preguntas encontraron respuesta en este encuentro en el que cerca de 80 profesionales expertos en esta nueva tendencia y empresas nacionales e internacionales aportaron sus experiencias y contaron sus casos de \u00e9xito para arrojar algo de luz a los participantes.<\/p>\n<p>A lo largo de toda la jornada, los ponentes llegados a las Islas Canarias desde pa\u00edses como Irlanda, B\u00e9lgica y Portugal, entre otros, representando a grandes empresas como Siteground, Work Human o Grow Remote, debatieron con profesionales y representantes de empresas nacionales y locales, como la Zona Especial Canaria, Proexca, el la Sociedad de Promoci\u00f3n Econ\u00f3mica de Gran Canaria, Philip Morris, Inetel o Hiperdino, entre otras, con el objetivo de entender c\u00f3mo este fen\u00f3meno est\u00e1 afectando a la econom\u00eda local y a la sociedad.<\/p>\n<blockquote><p>Cerca de 80 ponentes distribuidos en Gran Canaria, Tenerife y La Palma aportaron sus experiencias en relaci\u00f3n a esta tendencia<\/p><\/blockquote>\n<p><strong>Un evento \u00fanico<\/strong><\/p>\n<p>Participantes de Alemania, Irlanda, Reino Unido, Estados Unidos, Espa\u00f1a y otros muchos pa\u00edses conectaron con la repeople Conference de manera online o asistieron de manera presencial al encuentro en una de las tres sedes que, por primera vez, acogieron de manera simult\u00e1nea la conferencia.<\/p>\n<p>Gracias al apoyo de Turismo de Islas Canarias, el Patronato de Turismo de Gran Canaria, Tenerife Work&amp;Play, la Sociedad de Promoci\u00f3n Econ\u00f3mica de Gran Canaria y otras instituciones y empresas privadas, el encuentro, que en a\u00f1os anteriores se celebraba \u00fanicamente en Gran Canaria y en formato online, pudo adoptar este a\u00f1o este novedoso formato que cont\u00f3 con tres agendas simult\u00e1neas e independientes en Gran Canaria, Tenerife y en la isla de La Palma, que a pesar de las dificultades derivadas por la erupci\u00f3n del volc\u00e1n y el cierre del aeropuerto durante los d\u00edas previos a la celebraci\u00f3n del evento, pudo organizar una fant\u00e1stica jornada con una veintena de ponentes.<\/p>\n<p>El broche final al evento lo puso Jason Fried, cofundador y director de la plataforma Basecamp, un software de gesti\u00f3n de proyectos con sede en Chicago y l\u00edder en el mercado, cuya ponencia fue emitida en las tres sedes de manera simult\u00e1nea como cierre de la conferencia. Adem\u00e1s de hablar sobre su experiencia como trabajador remoto, Fried explic\u00f3 como la tecnolog\u00eda y el trabajo colaborativo es una parte fundamental para ser productivo trabajando desde cualquier parte del mundo.<\/p>\n<blockquote><p>Es el \u00fanico evento en Europa que trata de dar respuesta, desde distintas perspectivas, a las empresas que cada vez m\u00e1s se enfrentan al fen\u00f3meno del trabajo remoto<\/p><\/blockquote>\n<p>Un a\u00f1o m\u00e1s, la repeople Conference ha logrado convertirse en punto de encuentro entre empresas distribuidas, teletrabajadores, empresas de la industria del teletrabajo y talento internacional, para reforzar a las Islas Canarias como destino ideal para empresas localizadas en otros puntos con equipos remotos y distribuidos.<\/p>\n<p>Cabe recordar que adem\u00e1s, Canarias cuenta ya con m\u00e1s de un centenar de espacios de <em>coworking<\/em> y varios <em>coliving<\/em> adaptados a las necesidades de este perfil de profesionales, donde es posible compaginar c\u00f3modamente el trabajo con el esparcimiento, lo que sin duda posiciona al Archipi\u00e9lago en este sector.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alemania, Irlanda, Reino Unido, Estados Unidos, Espa\u00f1a y otros muchos pa\u00edses conectaron con la repeople Conference de manera online Cerca de 400 personas de 29 pa\u00edses han asistido esta semana a la sexta edici\u00f3n de la repeople Conference, el \u00fanico evento en Europa que analiza el trabajo remoto desde distintas perspectivas y este a\u00f1o, con [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":14783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"+400 personas de 29 pa\u00edses en repeople Conference","_yoast_wpseo_metadesc":"repeople Conference donde cerca de 400 personas de 29 pa\u00edses se reunieron en las Islas Canarias para compartir conocimientos y experiencias. &#x1F30D;&#x1F389;","footnotes":""},"categories":[150],"tags":[97,106,88,42,44,102,101,84],"class_list":["post-5959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-canarias","tag-fiscalidad","tag-gran-canaria","tag-impacto-economico","tag-islas-canarias","tag-la-palma-2","tag-tenerife-2","tag-trabajo-remoto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>+400 personas de 29 pa\u00edses en repeople Conference<\/title>\n<meta name=\"description\" content=\"repeople Conference donde cerca de 400 personas de 29 pa\u00edses se reunieron en las Islas Canarias para compartir conocimientos y experiencias. &#x1F30D;&#x1F389;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"+400 personas de 29 pa\u00edses en repeople Conference\" \/>\n<meta property=\"og:description\" content=\"repeople Conference donde cerca de 400 personas de 29 pa\u00edses se reunieron en las Islas Canarias para compartir conocimientos y experiencias. &#x1F30D;&#x1F389;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/\" \/>\n<meta property=\"og:site_name\" content=\"repeople\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rePeople.co\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-03T10:52:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-30T08:18:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.repeople.co\/wp-content\/uploads\/2021\/12\/Conferencia-de-repeople-celebrada-en-las-Islas-Canarias.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1066\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"repeople\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@repeopleco\" \/>\n<meta name=\"twitter:site\" content=\"@repeopleco\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"repeople\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/\"},\"author\":{\"name\":\"repeople\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/78e267c6c368c6962c10fdfff0de7266\"},\"headline\":\"Cerca de 400 personas de 29 pa\u00edses asistieron a la repeople Conference celebrada en las Islas Canarias\",\"datePublished\":\"2021-12-03T10:52:06+00:00\",\"dateModified\":\"2024-10-30T08:18:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/\"},\"wordCount\":735,\"publisher\":{\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2021\/12\/Conferencia-de-repeople-celebrada-en-las-Islas-Canarias.webp\",\"keywords\":[\"Canarias\",\"fiscalidad\",\"Gran Canaria\",\"Impacto econ\u00f3mico\",\"Islas Canarias\",\"La Palma\",\"Tenerife\",\"trabajo remoto\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/\",\"url\":\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/\",\"name\":\"+400 personas de 29 pa\u00edses en repeople Conference\",\"isPartOf\":{\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2021\/12\/Conferencia-de-repeople-celebrada-en-las-Islas-Canarias.webp\",\"datePublished\":\"2021-12-03T10:52:06+00:00\",\"dateModified\":\"2024-10-30T08:18:59+00:00\",\"description\":\"repeople Conference donde cerca de 400 personas de 29 pa\u00edses se reunieron en las Islas Canarias para compartir conocimientos y experiencias. &#x1F30D;&#x1F389;\",\"breadcrumb\":{\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#primaryimage\",\"url\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2021\/12\/Conferencia-de-repeople-celebrada-en-las-Islas-Canarias.webp\",\"contentUrl\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2021\/12\/Conferencia-de-repeople-celebrada-en-las-Islas-Canarias.webp\",\"width\":1066,\"height\":600,\"caption\":\"Conferencia de repeople celebrada en las Islas Canarias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.repeople.co\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cerca de 400 personas de 29 pa\u00edses asistieron a la repeople Conference celebrada en las Islas Canarias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#website\",\"url\":\"https:\/\/www.repeople.co\/es\/en\/\",\"name\":\"repeople\",\"description\":\"Dise\u00f1ando ecosistemas para teletrabajadores\",\"publisher\":{\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#organization\"},\"alternateName\":\"repeople\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.repeople.co\/es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#organization\",\"name\":\"repeople\",\"alternateName\":\"repeople\",\"url\":\"https:\/\/www.repeople.co\/es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-logo-2.png\",\"contentUrl\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-logo-2.png\",\"width\":762,\"height\":220,\"caption\":\"repeople\"},\"image\":{\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/rePeople.co\/\",\"https:\/\/x.com\/repeopleco\",\"https:\/\/www.instagram.com\/repeopleco\/\",\"https:\/\/www.linkedin.com\/company\/repeopleco\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/78e267c6c368c6962c10fdfff0de7266\",\"name\":\"repeople\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-symbol-1.png\",\"contentUrl\":\"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-symbol-1.png\",\"caption\":\"repeople\"},\"url\":\"https:\/\/www.repeople.co\/es\/author\/repeoplepr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"+400 personas de 29 pa\u00edses en repeople Conference","description":"repeople Conference donde cerca de 400 personas de 29 pa\u00edses se reunieron en las Islas Canarias para compartir conocimientos y experiencias. &#x1F30D;&#x1F389;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/","og_locale":"es_ES","og_type":"article","og_title":"+400 personas de 29 pa\u00edses en repeople Conference","og_description":"repeople Conference donde cerca de 400 personas de 29 pa\u00edses se reunieron en las Islas Canarias para compartir conocimientos y experiencias. &#x1F30D;&#x1F389;","og_url":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/","og_site_name":"repeople","article_publisher":"https:\/\/www.facebook.com\/rePeople.co\/","article_published_time":"2021-12-03T10:52:06+00:00","article_modified_time":"2024-10-30T08:18:59+00:00","og_image":[{"width":1066,"height":600,"url":"https:\/\/www.repeople.co\/wp-content\/uploads\/2021\/12\/Conferencia-de-repeople-celebrada-en-las-Islas-Canarias.webp","type":"image\/webp"}],"author":"repeople","twitter_card":"summary_large_image","twitter_creator":"@repeopleco","twitter_site":"@repeopleco","twitter_misc":{"Escrito por":"repeople","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#article","isPartOf":{"@id":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/"},"author":{"name":"repeople","@id":"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/78e267c6c368c6962c10fdfff0de7266"},"headline":"Cerca de 400 personas de 29 pa\u00edses asistieron a la repeople Conference celebrada en las Islas Canarias","datePublished":"2021-12-03T10:52:06+00:00","dateModified":"2024-10-30T08:18:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/"},"wordCount":735,"publisher":{"@id":"https:\/\/www.repeople.co\/es\/en\/#organization"},"image":{"@id":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repeople.co\/wp-content\/uploads\/2021\/12\/Conferencia-de-repeople-celebrada-en-las-Islas-Canarias.webp","keywords":["Canarias","fiscalidad","Gran Canaria","Impacto econ\u00f3mico","Islas Canarias","La Palma","Tenerife","trabajo remoto"],"articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/","url":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/","name":"+400 personas de 29 pa\u00edses en repeople Conference","isPartOf":{"@id":"https:\/\/www.repeople.co\/es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#primaryimage"},"image":{"@id":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.repeople.co\/wp-content\/uploads\/2021\/12\/Conferencia-de-repeople-celebrada-en-las-Islas-Canarias.webp","datePublished":"2021-12-03T10:52:06+00:00","dateModified":"2024-10-30T08:18:59+00:00","description":"repeople Conference donde cerca de 400 personas de 29 pa\u00edses se reunieron en las Islas Canarias para compartir conocimientos y experiencias. &#x1F30D;&#x1F389;","breadcrumb":{"@id":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#primaryimage","url":"https:\/\/www.repeople.co\/wp-content\/uploads\/2021\/12\/Conferencia-de-repeople-celebrada-en-las-Islas-Canarias.webp","contentUrl":"https:\/\/www.repeople.co\/wp-content\/uploads\/2021\/12\/Conferencia-de-repeople-celebrada-en-las-Islas-Canarias.webp","width":1066,"height":600,"caption":"Conferencia de repeople celebrada en las Islas Canarias"},{"@type":"BreadcrumbList","@id":"https:\/\/www.repeople.co\/es\/blog\/cerca-de-400-personas-de-29-paises-asistieron-a-la-repeople-conference-celebrada-en-las-islas-canarias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.repeople.co\/es\/"},{"@type":"ListItem","position":2,"name":"Cerca de 400 personas de 29 pa\u00edses asistieron a la repeople Conference celebrada en las Islas Canarias"}]},{"@type":"WebSite","@id":"https:\/\/www.repeople.co\/es\/en\/#website","url":"https:\/\/www.repeople.co\/es\/en\/","name":"repeople","description":"Dise\u00f1ando ecosistemas para teletrabajadores","publisher":{"@id":"https:\/\/www.repeople.co\/es\/en\/#organization"},"alternateName":"repeople","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.repeople.co\/es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.repeople.co\/es\/en\/#organization","name":"repeople","alternateName":"repeople","url":"https:\/\/www.repeople.co\/es\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repeople.co\/es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-logo-2.png","contentUrl":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-logo-2.png","width":762,"height":220,"caption":"repeople"},"image":{"@id":"https:\/\/www.repeople.co\/es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rePeople.co\/","https:\/\/x.com\/repeopleco","https:\/\/www.instagram.com\/repeopleco\/","https:\/\/www.linkedin.com\/company\/repeopleco"]},{"@type":"Person","@id":"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/78e267c6c368c6962c10fdfff0de7266","name":"repeople","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.repeople.co\/es\/en\/#\/schema\/person\/image\/","url":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-symbol-1.png","contentUrl":"https:\/\/www.repeople.co\/wp-content\/uploads\/2020\/08\/repeople-symbol-1.png","caption":"repeople"},"url":"https:\/\/www.repeople.co\/es\/author\/repeoplepr\/"}]}},"_links":{"self":[{"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/posts\/5959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/comments?post=5959"}],"version-history":[{"count":1,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/posts\/5959\/revisions"}],"predecessor-version":[{"id":5962,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/posts\/5959\/revisions\/5962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/media\/14783"}],"wp:attachment":[{"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/media?parent=5959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/categories?post=5959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.repeople.co\/es\/wp-json\/wp\/v2\/tags?post=5959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}